{"id":49682,"date":"2026-07-23T14:27:18","date_gmt":"2026-07-23T14:27:18","guid":{"rendered":"https:\/\/masicasas.com\/?post_type=property&#038;p=49682"},"modified":"2026-07-28T13:31:58","modified_gmt":"2026-07-28T13:31:58","slug":"casa-lumiere-lescala","status":"publish","type":"property","link":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/","title":{"rendered":"Casa Lumi\u00e8re, L&#8217;Escala"},"content":{"rendered":"<p>Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal.<\/p>\n<p>En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus materiales. La cocina, la carpinter\u00eda, los cerramientos y el conjunto de sus equipamientos reflejan un especial cuidado por cada detalle, convirti\u00e9ndola en una propiedad verdaderamente atemporal.<\/p>\n<p>En el exterior, podr\u00e1 disfrutar de una piscina privada, amplias terrazas soleadas, una zona de relax con tumbonas y una agradable \u00e1rea de barbacoa, ideal para compartir momentos en familia o con amigos. Una amplia rampa de acceso permite estacionar varios veh\u00edculos y conduce a un garaje cerrado. La propiedad dispone asimismo de generosos espacios de almacenamiento y de una sala dedicada al deporte y al bienestar.<\/p>\n<p>La zona de d\u00eda principal, situada en la misma planta, est\u00e1 compuesta por un amplio sal\u00f3n-comedor, una cocina totalmente equipada, dos dormitorios, dos ba\u00f1os y un despacho. En la planta superior, la vivienda revela una espectacular suite principal con vestidor, ba\u00f1o independiente y acceso directo a una terraza privada con impresionantes vistas al macizo del Montgr\u00ed y a los Pirineos.<\/p>\n<p>Situada en la Costa Brava, en L\u2019Escala, y pr\u00f3xima a las diferentes playas del municipio, esta propiedad es ideal tanto como residencia habitual como segunda residencia. Dispone de todas las comodidades necesarias para vivir durante todo el a\u00f1o: calefacci\u00f3n, aire acondicionado y prestaciones de alta gama.<\/p>\n<p>Una vivienda \u00fanica por descubrir, donde cada detalle ha sido concebido para ofrecer una calidad de vida incomparable en un entorno privilegiado.<\/p>\n<p><em>Algunes imatges han estat optimitzades amb intel\u00b7lig\u00e8ncia artificial.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal. En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49683,"parent":0,"menu_order":0,"template":"","property_type":[159],"property_status":[],"property_feature":[161,364,239,264,279,247,460,241,240,242,244,245,248,246,378,243,281,252,253,250,251,344,339],"property_label":[],"property_country":[],"property_state":[113],"property_city":[117],"property_area":[545],"class_list":["post-49682","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-casas","property_feature-aire-acondicionado-es","property_feature-amueblado-es","property_feature-armarios-empotrados-es","property_feature-aseo-es","property_feature-balcon-es","property_feature-buena-orientacion-es","property_feature-calefaccion-es","property_feature-calefaccion-central-es","property_feature-casa-independiente-es","property_feature-chimenea-es","property_feature-cierres-doble-vidrio-es","property_feature-cocina-equipada-es","property_feature-cocina-office-es","property_feature-garaje-es","property_feature-parking-exterior-es","property_feature-patio-es","property_feature-piscina-privada-es","property_feature-suite-con-bano-es","property_feature-terraza-es","property_feature-terraza-solarium-es","property_feature-trastero-es","property_feature-vestidor-es","property_feature-vistas-a-muntana-es","property_state-cataluna","property_city-l-escala-es","property_area-puig-sec-es"],"property_meta":{"_thumbnail_id":["49683"],"copied_media_ids":["a:0:{}"],"referenced_media_ids":["a:1:{i:0;i:49574;}"],"fave_currency_info":[""],"_vc_post_settings":["a:1:{s:10:\"vc_grid_id\";a:0:{}}"],"fave_property_size":["181"],"fave_property_size_prefix":["M2"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["4"],"fave_property_year":["1992"],"fave_property_map":["1"],"fave_property_map_address":["Carrer de la Vall d'Aran, l'Escala, Alt Empord\u00e0, Girona, Catalunya, 17130, Espa\u00f1a"],"fave_property_location":["42.1083543,3.1527442,15"],"houzez_geolocation_lat":["42.1083543"],"houzez_geolocation_long":["3.1527442"],"fave_property_country":["US"],"fave_additional_features_enable":["enable"],"fave_floor_plans_enable":["enable"],"houzez_featured_listing_date":["2026-07-28 13:31:59"],"fave_video_image":["84"],"fave_video_url":["https:\/\/youtu.be\/td4tCuGox18"],"fave_payment_status":["not_paid"],"fave_property_map_street_view":["show"],"_dp_original":["437"],"houzez_recently_viewed":["2026-09-02 06:35:06"],"houzez_views_by_date":["a:61:{s:10:\"05-26-2026\";i:3;s:10:\"05-27-2026\";i:1;s:10:\"06-10-2026\";i:1;s:10:\"06-16-2026\";i:1;s:10:\"06-17-2026\";i:1;s:10:\"06-19-2026\";i:1;s:10:\"06-25-2026\";i:1;s:10:\"06-26-2026\";i:1;s:10:\"06-30-2026\";i:1;s:10:\"07-10-2026\";i:1;s:10:\"07-12-2026\";i:3;s:10:\"07-14-2026\";i:1;s:10:\"07-16-2026\";i:4;s:10:\"07-17-2026\";i:3;s:10:\"07-18-2026\";i:8;s:10:\"07-19-2026\";i:1;s:10:\"07-20-2026\";i:1;s:10:\"07-21-2026\";i:4;s:10:\"07-22-2026\";i:1;s:10:\"07-23-2026\";i:4;s:10:\"07-24-2026\";i:1;s:10:\"07-25-2026\";i:2;s:10:\"07-26-2026\";i:1;s:10:\"07-27-2026\";i:1;s:10:\"07-28-2026\";i:3;s:10:\"07-29-2026\";i:1;s:10:\"07-30-2026\";i:1;s:10:\"07-31-2026\";i:1;s:10:\"08-01-2026\";i:1;s:10:\"08-02-2026\";i:1;s:10:\"08-03-2026\";i:1;s:10:\"08-04-2026\";i:1;s:10:\"08-05-2026\";i:1;s:10:\"08-06-2026\";i:1;s:10:\"08-07-2026\";i:1;s:10:\"08-08-2026\";i:1;s:10:\"08-09-2026\";i:1;s:10:\"08-10-2026\";i:1;s:10:\"08-11-2026\";i:2;s:10:\"08-12-2026\";i:1;s:10:\"08-13-2026\";i:3;s:10:\"08-14-2026\";i:1;s:10:\"08-15-2026\";i:1;s:10:\"08-16-2026\";i:1;s:10:\"08-17-2026\";i:1;s:10:\"08-18-2026\";i:1;s:10:\"08-19-2026\";i:2;s:10:\"08-20-2026\";i:2;s:10:\"08-21-2026\";i:1;s:10:\"08-22-2026\";i:1;s:10:\"08-23-2026\";i:1;s:10:\"08-24-2026\";i:1;s:10:\"08-25-2026\";i:1;s:10:\"08-26-2026\";i:1;s:10:\"08-27-2026\";i:1;s:10:\"08-28-2026\";i:1;s:10:\"08-29-2026\";i:1;s:10:\"08-30-2026\";i:1;s:10:\"08-31-2026\";i:1;s:10:\"09-01-2026\";i:1;s:10:\"09-02-2026\";i:1;}"],"houzez_total_property_views":["7940"],"fave_multiunit_plans_enable":["disable"],"fave_rating":["a:5:{i:1;i:0;i:2;i:0;i:3;i:0;i:4;i:0;i:5;i:0;}"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["0"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_wpml_word_count":["332"],"fave_property_id":["2541"],"_yoast_wpseo_metadesc":["Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal.En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus materiales. La cocina, la carpinter\u00eda, los cerramientos y el conjunto de sus equipamientos reflejan un especial cuidado por cada detalle, convirti\u00e9ndola en una propiedad verdaderamente atemporal.En el exterior, podr\u00e1 disfrutar de una piscina privada, amplias terrazas soleadas, una zona de relax con tumbonas y una agradable \u00e1rea de barbacoa, ideal para compartir momentos en familia o con amigos. Una amplia rampa de acceso permite estacionar varios veh\u00edculos y conduce a un garaje cerrado. La propiedad dispone asimismo de generosos espacios de almacenamiento y de una sala dedicada al deporte y al bienestar."],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["2"],"_yoast_wpseo_wordproof_timestamp":[""],"fave_show_price_placeholder":["0"],"fave_property_land":["400"],"fave_property_land_postfix":["M2"],"_yoast_wpseo_primary_property_type":[""],"_yoast_wpseo_primary_property_status":[""],"_yoast_wpseo_primary_property_feature":[""],"_yoast_wpseo_primary_property_label":[""],"_yoast_wpseo_primary_property_country":[""],"_yoast_wpseo_primary_property_state":[""],"_yoast_wpseo_primary_property_city":[""],"_yoast_wpseo_primary_property_area":[""],"cmplz_hide_cookiebanner":[""],"fave_property_price":["640000"],"fave_property_garage":["1"],"fave_energy_class":["G"],"fave_energy_global_index":["514"],"_edit_lock":["1785245406:2"],"_edit_last":["2"],"_last_translation_edit_mode":["native-editor"],"fave_prop_slider_image":["49574"],"fave_featured":["1"],"fave_property_images":["49574","49575","49576","49577","49578","49579","49580","49581","49582","49583","49584","49585","49586","49587","49588","49589","49590","49591","49592","49593","49594","49595","49596","49597","49598","49599","49600","49601","49602","49603","49604","49605","49606","49607","49608","49307"],"fave_agent_display_option":["agency_info"],"fave_property_agency":["2790"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa Lumi\u00e8re, L&#039;Escala - Mas i Casas<\/title>\n<meta name=\"description\" content=\"Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal.En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus materiales. La cocina, la carpinter\u00eda, los cerramientos y el conjunto de sus equipamientos reflejan un especial cuidado por cada detalle, convirti\u00e9ndola en una propiedad verdaderamente atemporal.En el exterior, podr\u00e1 disfrutar de una piscina privada, amplias terrazas soleadas, una zona de relax con tumbonas y una agradable \u00e1rea de barbacoa, ideal para compartir momentos en familia o con amigos. Una amplia rampa de acceso permite estacionar varios veh\u00edculos y conduce a un garaje cerrado. La propiedad dispone asimismo de generosos espacios de almacenamiento y de una sala dedicada al deporte y al bienestar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa Lumi\u00e8re, L&#039;Escala - Mas i Casas\" \/>\n<meta property=\"og:description\" content=\"Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal.En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus materiales. La cocina, la carpinter\u00eda, los cerramientos y el conjunto de sus equipamientos reflejan un especial cuidado por cada detalle, convirti\u00e9ndola en una propiedad verdaderamente atemporal.En el exterior, podr\u00e1 disfrutar de una piscina privada, amplias terrazas soleadas, una zona de relax con tumbonas y una agradable \u00e1rea de barbacoa, ideal para compartir momentos en familia o con amigos. Una amplia rampa de acceso permite estacionar varios veh\u00edculos y conduce a un garaje cerrado. La propiedad dispone asimismo de generosos espacios de almacenamiento y de una sala dedicada al deporte y al bienestar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/\" \/>\n<meta property=\"og:site_name\" content=\"Mas i Casas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T13:31:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masicasas.com\/wp-content\/uploads\/2026\/07\/1-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/masicasas.com\\\/es\\\/property\\\/casa-lumiere-lescala\\\/\",\"url\":\"https:\\\/\\\/masicasas.com\\\/es\\\/property\\\/casa-lumiere-lescala\\\/\",\"name\":\"Casa Lumi\u00e8re, L'Escala - Mas i Casas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/masicasas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/masicasas.com\\\/es\\\/property\\\/casa-lumiere-lescala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/masicasas.com\\\/es\\\/property\\\/casa-lumiere-lescala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/masicasas.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/1-5.png\",\"datePublished\":\"2026-07-23T14:27:18+00:00\",\"dateModified\":\"2026-07-28T13:31:58+00:00\",\"description\":\"Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal.En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus materiales. La cocina, la carpinter\u00eda, los cerramientos y el conjunto de sus equipamientos reflejan un especial cuidado por cada detalle, convirti\u00e9ndola en una propiedad verdaderamente atemporal.En el exterior, podr\u00e1 disfrutar de una piscina privada, amplias terrazas soleadas, una zona de relax con tumbonas y una agradable \u00e1rea de barbacoa, ideal para compartir momentos en familia o con amigos. Una amplia rampa de acceso permite estacionar varios veh\u00edculos y conduce a un garaje cerrado. La propiedad dispone asimismo de generosos espacios de almacenamiento y de una sala dedicada al deporte y al bienestar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/masicasas.com\\\/es\\\/property\\\/casa-lumiere-lescala\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/masicasas.com\\\/es\\\/property\\\/casa-lumiere-lescala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/masicasas.com\\\/es\\\/property\\\/casa-lumiere-lescala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/masicasas.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/1-5.png\",\"contentUrl\":\"https:\\\/\\\/masicasas.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/1-5.png\",\"width\":1448,\"height\":1086},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/masicasas.com\\\/es\\\/property\\\/casa-lumiere-lescala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/masicasas.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/masicasas.com\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casa Lumi\u00e8re, L&#8217;Escala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/masicasas.com\\\/#website\",\"url\":\"https:\\\/\\\/masicasas.com\\\/\",\"name\":\"Mas i Casas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/masicasas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/masicasas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/masicasas.com\\\/#organization\",\"name\":\"Ag\u00e8ncia Immobili\u00e0ria l`'Escala, Costa brava - Mas i Casas\",\"alternateName\":\"Mas i Casas\",\"url\":\"https:\\\/\\\/masicasas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/masicasas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/masicasas.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-LOGO-MAS-I-CASAS-GOOD.jpg\",\"contentUrl\":\"https:\\\/\\\/masicasas.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-LOGO-MAS-I-CASAS-GOOD.jpg\",\"width\":512,\"height\":512,\"caption\":\"Ag\u00e8ncia Immobili\u00e0ria l`'Escala, Costa brava - Mas i Casas\"},\"image\":{\"@id\":\"https:\\\/\\\/masicasas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa Lumi\u00e8re, L'Escala - Mas i Casas","description":"Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal.En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus materiales. La cocina, la carpinter\u00eda, los cerramientos y el conjunto de sus equipamientos reflejan un especial cuidado por cada detalle, convirti\u00e9ndola en una propiedad verdaderamente atemporal.En el exterior, podr\u00e1 disfrutar de una piscina privada, amplias terrazas soleadas, una zona de relax con tumbonas y una agradable \u00e1rea de barbacoa, ideal para compartir momentos en familia o con amigos. Una amplia rampa de acceso permite estacionar varios veh\u00edculos y conduce a un garaje cerrado. La propiedad dispone asimismo de generosos espacios de almacenamiento y de una sala dedicada al deporte y al bienestar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/","og_locale":"es_ES","og_type":"article","og_title":"Casa Lumi\u00e8re, L'Escala - Mas i Casas","og_description":"Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal.En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus materiales. La cocina, la carpinter\u00eda, los cerramientos y el conjunto de sus equipamientos reflejan un especial cuidado por cada detalle, convirti\u00e9ndola en una propiedad verdaderamente atemporal.En el exterior, podr\u00e1 disfrutar de una piscina privada, amplias terrazas soleadas, una zona de relax con tumbonas y una agradable \u00e1rea de barbacoa, ideal para compartir momentos en familia o con amigos. Una amplia rampa de acceso permite estacionar varios veh\u00edculos y conduce a un garaje cerrado. La propiedad dispone asimismo de generosos espacios de almacenamiento y de una sala dedicada al deporte y al bienestar.","og_url":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/","og_site_name":"Mas i Casas","article_modified_time":"2026-07-28T13:31:58+00:00","og_image":[{"url":"https:\/\/masicasas.com\/wp-content\/uploads\/2026\/07\/1-5.png","width":1024,"height":768,"type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/","url":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/","name":"Casa Lumi\u00e8re, L'Escala - Mas i Casas","isPartOf":{"@id":"https:\/\/masicasas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/#primaryimage"},"image":{"@id":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/#primaryimage"},"thumbnailUrl":"https:\/\/masicasas.com\/wp-content\/uploads\/2026\/07\/1-5.png","datePublished":"2026-07-23T14:27:18+00:00","dateModified":"2026-07-28T13:31:58+00:00","description":"Idealmente orientada, esta magn\u00edfica propiedad disfruta de una excelente exposici\u00f3n solar durante todo el a\u00f1o. Moderna, luminosa, pr\u00e1ctica y funcional, ofrece un estilo de vida excepcional que combina elegancia, confort y un car\u00e1cter atemporal.En perfecto estado de conservaci\u00f3n, esta vivienda destaca por sus amplios espacios, sus excelentes acabados y la notable calidad de sus materiales. La cocina, la carpinter\u00eda, los cerramientos y el conjunto de sus equipamientos reflejan un especial cuidado por cada detalle, convirti\u00e9ndola en una propiedad verdaderamente atemporal.En el exterior, podr\u00e1 disfrutar de una piscina privada, amplias terrazas soleadas, una zona de relax con tumbonas y una agradable \u00e1rea de barbacoa, ideal para compartir momentos en familia o con amigos. Una amplia rampa de acceso permite estacionar varios veh\u00edculos y conduce a un garaje cerrado. La propiedad dispone asimismo de generosos espacios de almacenamiento y de una sala dedicada al deporte y al bienestar.","breadcrumb":{"@id":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/#primaryimage","url":"https:\/\/masicasas.com\/wp-content\/uploads\/2026\/07\/1-5.png","contentUrl":"https:\/\/masicasas.com\/wp-content\/uploads\/2026\/07\/1-5.png","width":1448,"height":1086},{"@type":"BreadcrumbList","@id":"https:\/\/masicasas.com\/es\/property\/casa-lumiere-lescala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/masicasas.com\/es\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/masicasas.com\/property\/"},{"@type":"ListItem","position":3,"name":"Casa Lumi\u00e8re, L&#8217;Escala"}]},{"@type":"WebSite","@id":"https:\/\/masicasas.com\/#website","url":"https:\/\/masicasas.com\/","name":"Mas i Casas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/masicasas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masicasas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/masicasas.com\/#organization","name":"Ag\u00e8ncia Immobili\u00e0ria l`'Escala, Costa brava - Mas i Casas","alternateName":"Mas i Casas","url":"https:\/\/masicasas.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/masicasas.com\/#\/schema\/logo\/image\/","url":"https:\/\/masicasas.com\/wp-content\/uploads\/2024\/07\/cropped-LOGO-MAS-I-CASAS-GOOD.jpg","contentUrl":"https:\/\/masicasas.com\/wp-content\/uploads\/2024\/07\/cropped-LOGO-MAS-I-CASAS-GOOD.jpg","width":512,"height":512,"caption":"Ag\u00e8ncia Immobili\u00e0ria l`'Escala, Costa brava - Mas i Casas"},"image":{"@id":"https:\/\/masicasas.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/properties\/49682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":3,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/properties\/49682\/revisions"}],"predecessor-version":[{"id":49726,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/properties\/49682\/revisions\/49726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/media\/49683"}],"wp:attachment":[{"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/media?parent=49682"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/property_type?post=49682"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/property_status?post=49682"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/property_feature?post=49682"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/property_label?post=49682"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/property_country?post=49682"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/property_state?post=49682"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/property_city?post=49682"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/masicasas.com\/es\/wp-json\/wp\/v2\/property_area?post=49682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}